 {"id":20051,"date":"2022-12-27T08:00:10","date_gmt":"2022-12-27T06:00:10","guid":{"rendered":"https:\/\/www.nexeimpressions.com\/?post_type=portfolio_page&#038;p=20051"},"modified":"2022-12-23T12:26:33","modified_gmt":"2022-12-23T10:26:33","slug":"els-papers-de-la-guerra-enserio","status":"publish","type":"portfolio_page","link":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/","title":{"rendered":"Els Papers de la Guerra &#8211; ENSERIO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<\/p>\n<h1>Els Papers de la Guerra<\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text]<\/p>\n<h2>ENSERIO<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text]<\/p>\n<p class=\"p2\">Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de <a href=\"https:\/\/www.verkami.com\/projects\/34109-papers-de-la-guerra-pepe-castells-i-pubill\" target=\"_blank\" rel=\"noopener\"><strong>Els Papers de la Guerra<\/strong><\/a>, editado por la familia de Pepe Castells y Pubill, y coordinado y dise\u00f1ado por el estudio <strong><a href=\"https:\/\/www.enserio.ws\/ca\/projectes\" target=\"_blank\" rel=\"noopener\">ENSERIO<\/a><\/strong> de Banyoles. Un testimonio intrahist\u00f3rico, uno muy particular y extraordinario, de los muchos que sacudieron a toda una generaci\u00f3n y de los que todos nosotros somos hijos, nietos, bisnietos o incluso tataranietos, en algunos casos. La visi\u00f3n y perspectiva de una tragedia, la Guerra Civil espa\u00f1ola, magn\u00edficamente documentado por el autor y protagonista de esta historia personal, que sus nietos han decidido publicar por el gran valor que representa.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p2\">El conjunto de documentos ha sido magn\u00edficamente dise\u00f1ado. Desde el concepto gr\u00e1fico, hasta la elecci\u00f3n de los materiales.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p2\">En\u00a0Nexe Impresiones\u00a0hemos asesorado, coordinado, seleccionado, impreso, encuadernado y velado para que todo el proceso gr\u00e1fico reflejara el esp\u00edritu que la familia como editores, y los dise\u00f1adores nos pidieron. Un proceso de producci\u00f3n gr\u00e1fica que ha supuesto la coordinaci\u00f3n y supervisi\u00f3n de varios talleres y obradores gr\u00e1ficos.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<strong>Ficha t\u00e9cnica:<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text]<strong>Dise\u00f1o:<\/strong> Enserio.com<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Libro<\/strong><br \/>\nFormato: 16,5 x 23,5 cm<br \/>\nP\u00e1ginas: 224 interiores + cubiertas i d\u00edptico<br \/>\nImpresi\u00f3n Interior: 4+4 LED UV<br \/>\nCubierta: 1+1<br \/>\nPapel<br \/>\nInterior: Arena Natural Bulk de 100 g.<br \/>\nCubierta: Fedrigoni Materica Verdigris de 360 \u200b\u200bg.<br \/>\nEncuadernado: cosido en hilo visto color blanco<br \/>\nAcabados: estampaci\u00f3n negra 50% de superficie<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Diario<\/strong><br \/>\nFormato: 165, x 23,5 cm<br \/>\nP\u00e1ginas: 16 p\u00e1ginas<br \/>\nImpresi\u00f3n: 4 + 4 LED UV<br \/>\nPapel: Cyclus offset de 70 g.<br \/>\nEncuadernado: juntos y encartado, replegado, y doble replegado<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Libreta<\/strong><br \/>\nFormato: 16,5 x 23,5 cm<br \/>\nP\u00e1ginas: 118 + 8<br \/>\nImpresi\u00f3n Interior: 1+1<br \/>\nCubierta: Materica Pitch de 360 \u200b\u200bg. a 1+1<br \/>\nPapel Interior: Arena Natural Bulk de 120 g.<br \/>\nCubierta : Fedrigoni Materica Pitch de 360 \u200b\u200bg.<br \/>\nEncuadernado: wire-o met\u00e1lico color cobre<br \/>\nAcabados: estampaci\u00f3n negra 50% de superficie<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Litografia <\/strong><br \/>\nFormato cerrado: 16,5 x 23,5 cm<br \/>\nPapel: cart\u00f3n bigris de 2 mm<br \/>\nImpresi\u00f3n: Serigraf\u00eda negra<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Postal <\/strong><br \/>\nFormato: 90 x 139 mm<br \/>\nPapel: Arena Natural Rough de 300 g.<br \/>\nImpresi\u00f3n: 4+1<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Caja<\/strong><br \/>\nPackaging personalizado<br \/>\nFormato abierto: 48,40 x 47 cm<br \/>\nSoporte: Microcanal E Kraft 1700 \u00b5<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Anverso<\/strong><br \/>\nImpresi\u00f3n a una cara en CMYK<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Reverso<\/strong><br \/>\nTroquelado[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb60px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text] Els Papers de la Guerra [\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text] ENSERIO [\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text] Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la familia de Pepe Castells y Pubill,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19988,"menu_order":309,"comment_status":"open","ping_status":"closed","template":"","portfolio_category":[498],"portfolio_tag":[],"class_list":["post-20051","portfolio_page","type-portfolio_page","status-publish","has-post-thumbnail","hentry","portfolio_category-libros-de-artista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions<\/title>\n<meta name=\"description\" content=\"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions\" \/>\n<meta property=\"og:description\" content=\"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/\" \/>\n<meta property=\"og:site_name\" content=\"Nexe Impressions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nexeimpressions\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/\",\"url\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/\",\"name\":\"Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions\",\"isPartOf\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg\",\"datePublished\":\"2022-12-27T06:00:10+00:00\",\"description\":\"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.\",\"breadcrumb\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage\",\"url\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg\",\"contentUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nexeimpressions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Els Papers de la Guerra &#8211; ENSERIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\",\"url\":\"https:\/\/nexeimpressions.com\/es\/\",\"name\":\"Nexe Impressions\",\"description\":\"Print worthy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions","description":"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/","og_locale":"es_ES","og_type":"article","og_title":"Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions","og_description":"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.","og_url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/","og_site_name":"Nexe Impressions","article_publisher":"https:\/\/www.facebook.com\/nexeimpressions","og_image":[{"width":1500,"height":1000,"url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/","url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/","name":"Els Papers de la Guerra - ENSERIO &#8211; Nexe Impressions","isPartOf":{"@id":"https:\/\/nexeimpressions.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage"},"image":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage"},"thumbnailUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg","datePublished":"2022-12-27T06:00:10+00:00","description":"Els Papers de la Guerra ENSERIO Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Els Papers de la Guerra, editado por la Nos ha hecho una gran ilusi\u00f3n poder participar en este entra\u00f1able proyecto de Papers de la Guerra, editado por la familia de Pep Castells y Pubill, y coordinado y dise\u00f1ado por el estudio ENSERIO de Banyoles.","breadcrumb":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#primaryimage","url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg","contentUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2022\/12\/MG_0430.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/els-papers-de-la-guerra-enserio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nexeimpressions.com\/es\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/"},{"@type":"ListItem","position":3,"name":"Els Papers de la Guerra &#8211; ENSERIO"}]},{"@type":"WebSite","@id":"https:\/\/nexeimpressions.com\/es\/#website","url":"https:\/\/nexeimpressions.com\/es\/","name":"Nexe Impressions","description":"Print worthy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page\/20051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page"}],"about":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/types\/portfolio_page"}],"author":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/comments?post=20051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media\/19988"}],"wp:attachment":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media?parent=20051"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=20051"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=20051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}