 {"id":20473,"date":"2023-03-02T10:00:20","date_gmt":"2023-03-02T09:00:20","guid":{"rendered":"https:\/\/www.nexeimpressions.com\/?post_type=portfolio_page&#038;p=20473"},"modified":"2023-03-02T10:29:17","modified_gmt":"2023-03-02T09:29:17","slug":"botiga-hermes-barcelona-hermes","status":"publish","type":"portfolio_page","link":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/","title":{"rendered":"Tienda H\u00e8rmes Barcelona &#8211; H\u00e8rmes"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<\/p>\n<h1>Tienda H\u00e8rmes Barcelona<\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text]<\/p>\n<h2>H\u00e8rmes<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb60px\u00bb][vc_column_text]<\/p>\n<p><a href=\"https:\/\/www.hermes.com\/es\/es\/\"><strong>Herm\u00e8s<\/strong><\/a> abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico oasis de artesan\u00eda, luz y gusto por los detalles; recogiendo la esencia del <em>savoir-faire<\/em> de la marca de lujo franc\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p>Bajo la direcci\u00f3n de arte de <strong><a href=\"https:\/\/apartamentostudios.com\/\">Apartamento Studios<\/a> <\/strong>de Barcelona se nos encomienda a <a href=\"https:\/\/agpograf.com\/es\/\"><strong>Agpograf<\/strong><\/a> y <strong>Nexe Impressions<\/strong>\u00a0la impresi\u00f3n y acabados de las invitaciones que constan de un <strong>sobre<\/strong> sellado con una <strong>etiqueta<\/strong> y una <strong>invitaci\u00f3n<\/strong> en formato cuadr\u00edptico. Con un acabado en relieve seco de mucha precisi\u00f3n e impreso en LED UV sobre un papel de artesan\u00eda de <a href=\"https:\/\/paper.fedrigoni.com\/esp\/\"><strong>Fedrigoni Papers<\/strong><\/a>, el Old Mill Bianco.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<strong>Especificaciones<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb30px\u00bb][vc_column_text]<strong>SOBRE<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text]<\/p>\n<p><strong>Impresi\u00f3n<\/strong><\/p>\n<p>LED UV a 4\/0 tintas Pantone<\/p>\n<p><strong>Papel<\/strong><\/p>\n<p><a href=\"https:\/\/paper.fedrigoni.com\/esp\/serie\/old-mill\/\">Old Mill Bianco<\/a> de 190 g<\/p>\n<p><strong>Acabados<\/strong><\/p>\n<p>Troquel<\/p>\n<p>Sellado con etiqueta<\/p>\n<p>&nbsp;<\/p>\n<p><strong>ETIQUETA<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text]<\/p>\n<p><strong>Impresi\u00f3n<\/strong><\/p>\n<p>A 1\/0 tintas<\/p>\n<p><strong>Papel<\/strong><\/p>\n<p>Offset blanco<\/p>\n<p><strong>Acabados<\/strong><\/p>\n<p>Troquel<\/p>\n<p>&nbsp;<\/p>\n<p><strong>INVITACI\u00d3N<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb15px\u00bb][vc_column_text]<\/p>\n<p><strong>Impresi\u00f3n<\/strong><\/p>\n<p>LED UV a 4\/4 tintas Pantone<\/p>\n<p><strong>Papel<\/strong><\/p>\n<p>Old Mill Premium White de 250 g<\/p>\n<p><strong>Acabados<\/strong><\/p>\n<p>Relieve seco, traspasando al reverso del papel<\/p>\n<p>Grabados<\/p>\n<p>Cuadr\u00edptico hendido y plegado en acorde\u00f3n<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb60px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text] Tienda H\u00e8rmes Barcelona [\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text] H\u00e8rmes [\/vc_column_text][vc_empty_space height=\u00bb60px\u00bb][vc_column_text] Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico oasis de artesan\u00eda, luz y gusto por&#8230;<\/p>\n","protected":false},"author":1,"featured_media":20470,"menu_order":290,"comment_status":"open","ping_status":"closed","template":"","portfolio_category":[],"portfolio_tag":[295,298,494,486],"class_list":["post-20473","portfolio_page","type-portfolio_page","status-publish","has-post-thumbnail","hentry","portfolio_tag-led-uv-es","portfolio_tag-relieve-seco","portfolio_tag-tintas-pantone","portfolio_tag-tintes-pantone-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions<\/title>\n<meta name=\"description\" content=\"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions\" \/>\n<meta property=\"og:description\" content=\"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/\" \/>\n<meta property=\"og:site_name\" content=\"Nexe Impressions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nexeimpressions\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T09:29:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/\",\"url\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/\",\"name\":\"Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions\",\"isPartOf\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg\",\"datePublished\":\"2023-03-02T09:00:20+00:00\",\"dateModified\":\"2023-03-02T09:29:17+00:00\",\"description\":\"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.\",\"breadcrumb\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage\",\"url\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg\",\"contentUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nexeimpressions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tienda H\u00e8rmes Barcelona &#8211; H\u00e8rmes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\",\"url\":\"https:\/\/nexeimpressions.com\/es\/\",\"name\":\"Nexe Impressions\",\"description\":\"Print worthy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions","description":"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/","og_locale":"es_ES","og_type":"article","og_title":"Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions","og_description":"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.","og_url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/","og_site_name":"Nexe Impressions","article_publisher":"https:\/\/www.facebook.com\/nexeimpressions","article_modified_time":"2023-03-02T09:29:17+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/","url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/","name":"Tienda H\u00e8rmes Barcelona - H\u00e8rmes &#8211; Nexe Impressions","isPartOf":{"@id":"https:\/\/nexeimpressions.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage"},"image":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage"},"thumbnailUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg","datePublished":"2023-03-02T09:00:20+00:00","dateModified":"2023-03-02T09:29:17+00:00","description":"Tienda H\u00e8rmes Barcelona H\u00e8rmes Herm\u00e8s abre en Barcelona su mayor boutique en Espa\u00f1a, y la \u00fanica que cuenta con sal\u00f3n privado. Se trata de un aut\u00e9ntico Con motivo de la inauguraci\u00f3n de la tienda de H\u00e8rmes en Barcelona y bajo la direcci\u00f3n de arte de Apartamento Studios, imprimimos estas invitaciones con un acabado en relieve seco.","breadcrumb":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#primaryimage","url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg","contentUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2023\/03\/1000x1000_IMG_0022.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/botiga-hermes-barcelona-hermes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nexeimpressions.com\/es\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/"},{"@type":"ListItem","position":3,"name":"Tienda H\u00e8rmes Barcelona &#8211; H\u00e8rmes"}]},{"@type":"WebSite","@id":"https:\/\/nexeimpressions.com\/es\/#website","url":"https:\/\/nexeimpressions.com\/es\/","name":"Nexe Impressions","description":"Print worthy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page\/20473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page"}],"about":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/types\/portfolio_page"}],"author":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/comments?post=20473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media\/20470"}],"wp:attachment":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media?parent=20473"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=20473"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=20473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}