 {"id":24863,"date":"2025-06-26T15:00:45","date_gmt":"2025-06-26T13:00:45","guid":{"rendered":"https:\/\/nexeimpressions.com\/?post_type=portfolio_page&#038;p=24863"},"modified":"2025-06-26T14:54:21","modified_gmt":"2025-06-26T12:54:21","slug":"cosmica-xocolata","status":"publish","type":"portfolio_page","link":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/","title":{"rendered":"C\u00f2smica &#8211; Chocolate"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<\/p>\n<h1>Chocolate<\/h1>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb20px\u00bb][vc_column_text]<\/p>\n<h2>C\u00f2smica<\/h2>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb60px\u00bb][vc_column_text]<\/p>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p><strong>C\u00f2smica<\/strong> es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y <em>social media<\/em>, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.<\/p>\n<p>&nbsp;<\/p>\n<p>Como muestra de agradecimiento a sus clientes, C\u00f2smica entrega un chocolate artesanal elaborado por la <strong>Pastisseria Serra<\/strong> de Sant Hip\u00f2lit de Voltreg\u00e0, un establecimiento centenario donde la cuarta generaci\u00f3n de la familia Serra trabaja creando productos de calidad con artesan\u00eda y creatividad.<\/p>\n<p>&nbsp;<\/p>\n<p>El dise\u00f1o del packaging es obra del equipo de C\u00f2smica y la producci\u00f3n corre a cargo de <strong>Nexe Impressions<\/strong>. El envoltorio consta de una bandeja y una faja en dos modelos diferentes, todo impreso con la tecnolog\u00eda de <strong>impresi\u00f3n digital de HP Indigo<\/strong> sobre el papel Old Mill Premium White de <strong>Fedrigoni Paper<\/strong>.<\/p>\n<p>[\/vc_column_text][vc_empty_space height=\u00bb60px\u00bb][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_column_text]<strong>Especificaciones<\/strong>[\/vc_column_text][vc_empty_space height=\u00bb30px\u00bb][vc_column_text]<strong>Formato<\/strong><\/p>\n<p>Bandeja: 20,2 x 14,7 cm<\/p>\n<p>Faja: 8 x 33 cm<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Papel<\/strong><\/p>\n<p>Old Mill Premium White 300 g de <strong>Fedrigoni Paper<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Impresi\u00f3n<\/strong><\/p>\n<p>Impresi\u00f3n digital HP Indigo<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Acabados<\/strong><\/p>\n<p>Troquelado y engomado de la faja<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css_animation=\u00bb\u00bb row_type=\u00bbrow\u00bb use_row_as_full_screen_section=\u00bbno\u00bb type=\u00bbfull_width\u00bb angled_section=\u00bbno\u00bb text_align=\u00bbleft\u00bb background_image_as_pattern=\u00bbwithout_pattern\u00bb][vc_column][vc_empty_space height=\u00bb50px\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.<\/p>\n","protected":false},"author":1,"featured_media":24860,"menu_order":104,"comment_status":"open","ping_status":"closed","template":"","portfolio_category":[485],"portfolio_tag":[523,294],"class_list":["post-24863","portfolio_page","type-portfolio_page","status-publish","has-post-thumbnail","hentry","portfolio_category-packaging-es","portfolio_tag-encuny-es","portfolio_tag-hp-indigo-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f2smica - Chocolate &#8211; Nexe Impressions<\/title>\n<meta name=\"description\" content=\"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f2smica - Chocolate &#8211; Nexe Impressions\" \/>\n<meta property=\"og:description\" content=\"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/\" \/>\n<meta property=\"og:site_name\" content=\"Nexe Impressions\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/nexeimpressions\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/\",\"url\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/\",\"name\":\"C\u00f2smica - Chocolate &#8211; Nexe Impressions\",\"isPartOf\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg\",\"datePublished\":\"2025-06-26T13:00:45+00:00\",\"description\":\"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.\",\"breadcrumb\":{\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage\",\"url\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg\",\"contentUrl\":\"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Cardboard Packaging Cosmica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/nexeimpressions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\/\/nexeimpressions.com\/es\/portfolio_page\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C\u00f2smica &#8211; Chocolate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/nexeimpressions.com\/es\/#website\",\"url\":\"https:\/\/nexeimpressions.com\/es\/\",\"name\":\"Nexe Impressions\",\"description\":\"Print worthy\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f2smica - Chocolate &#8211; Nexe Impressions","description":"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f2smica - Chocolate &#8211; Nexe Impressions","og_description":"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.","og_url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/","og_site_name":"Nexe Impressions","article_publisher":"https:\/\/www.facebook.com\/nexeimpressions","og_image":[{"width":1000,"height":1000,"url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/","url":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/","name":"C\u00f2smica - Chocolate &#8211; Nexe Impressions","isPartOf":{"@id":"https:\/\/nexeimpressions.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage"},"image":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage"},"thumbnailUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg","datePublished":"2025-06-26T13:00:45+00:00","description":"C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada. C\u00f2smica es una agencia de comunicaci\u00f3n de Barcelona que da voz a marcas, eventos y proyectos culturales con servicios de estrategia, prensa, contenidos y social media, con m\u00e1s de veinte a\u00f1os de experiencia y una mirada personalizada.","breadcrumb":{"@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#primaryimage","url":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg","contentUrl":"https:\/\/nexeimpressions.com\/wp-content\/uploads\/2025\/06\/Cosmica-Cardboard-Packaging_1000x1000.jpg","width":1000,"height":1000,"caption":"Cardboard Packaging Cosmica"},{"@type":"BreadcrumbList","@id":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/cosmica-xocolata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nexeimpressions.com\/es\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/nexeimpressions.com\/es\/portfolio_page\/"},{"@type":"ListItem","position":3,"name":"C\u00f2smica &#8211; Chocolate"}]},{"@type":"WebSite","@id":"https:\/\/nexeimpressions.com\/es\/#website","url":"https:\/\/nexeimpressions.com\/es\/","name":"Nexe Impressions","description":"Print worthy","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nexeimpressions.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page\/24863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_page"}],"about":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/types\/portfolio_page"}],"author":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/comments?post=24863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media\/24860"}],"wp:attachment":[{"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/media?parent=24863"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_category?post=24863"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/nexeimpressions.com\/es\/wp-json\/wp\/v2\/portfolio_tag?post=24863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}